{"id":29168,"date":"2017-05-05T03:55:00","date_gmt":"2017-05-05T03:55:00","guid":{"rendered":"http:\/\/audiocenter.cc\/malaysia-calvary-city-church-instalo-el-sistema-audiocenter-k-la28\/"},"modified":"2023-09-27T06:23:30","modified_gmt":"2023-09-27T06:23:30","slug":"malaysia-calvary-city-church-instalo-el-sistema-audiocenter-k-la28","status":"publish","type":"post","link":"https:\/\/audiocenter.com\/es\/malaysia-calvary-city-church-instalo-el-sistema-audiocenter-k-la28\/","title":{"rendered":"Malaysia Calvary City Church instal\u00f3 el sistema Audiocenter K-LA28"},"content":{"rendered":"\n<p><\/p>\n\n<p>Calvary City Church Taman Tan Sri Yaacob Jobor Bharu buscando una ampliaci\u00f3n de su actual local de culto, se ha convertido en la primera iglesia de Malasia en instalar el line array K-LA28 de Audiocenter. De ser una peque\u00f1a iglesia basada en una tienda, actualmente se ha expandido a un espacio de culto de 8000 pies cuadrados. Con esto en mente, la iglesia necesitaba un sistema de alimentaci\u00f3n adaptable, de cobertura uniforme, alta inteligibilidad, claridad de palabra hablada y rendimiento de banda para alojarlo en el nuevo local.<\/p>\n\n<p>Durante la demostraci\u00f3n, el p\u00e1rroco y los miembros de su comit\u00e9 se sintieron muy atra\u00eddos por la calidad de audio y el valor que la marca y el producto Audiocenter aportan a la iglesia. Se despliegan 2 grupos de 4 unidades de K-LA28 como configuraci\u00f3n LR para cubrir toda la sala de 40 metros de longitud. 2 unidades de subwoofer PF218B+ ocultas bajo el escenario como refuerzo de baja frecuencia.<\/p>\n\n<p>El 23 de abril de 2017, Calvary City Church celebr\u00f3 un &#8220;Servicio de dedicaci\u00f3n del nuevo edificio de la iglesia&#8221;. Adem\u00e1s de celebrar el nuevo local, tambi\u00e9n es un hito de la Calvary City Church desde sus humildes comienzos hasta ahora, una iglesia sin techo, sin muros y que llega a la sociedad. El pastor de la iglesia, el reverendo Y. K. Chong, est\u00e1 muy orgulloso del nuevo local y del sistema de audio. Al describir el sistema de audio: &#8220;El sistema cumpli\u00f3 todas mis expectativas. El mensaje de los l\u00edderes de la iglesia fue limpio y claro, la actuaci\u00f3n de la banda fue magn\u00edfica y lo m\u00e1s importante es que no hubo ning\u00fan contratiempo durante todo el evento. Todo funcion\u00f3 a la perfecci\u00f3n&#8221;.<\/p>\n\n<p>El sistema K-LA28 fue propuesto por el distribuidor de Audiocenter en Malasia, AV Electronics Marketing Sdn Bhd. El distribuidor tambi\u00e9n actu\u00f3 como asesor de audio para todo el proyecto. El equipo t\u00e9cnico formado por K.L Chia, J.C Lai y Eric Chee, con numerosas consultas de grandes proyectos a sus espaldas, trabaja en la simulaci\u00f3n de Ease Focus, el ajuste de SMART 8 y el ajuste fino por o\u00eddos, respectivamente. El equipo t\u00e9cnico est\u00e1 muy satisfecho con el resultado final, ya que resulta ser el rendimiento previsto.<\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"680\" height=\"453\" data-id=\"22756\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/MG_9953.jpg\" alt=\"\" class=\"wp-image-22756\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9953.jpg 680w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9953-300x200.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"680\" height=\"453\" data-id=\"22744\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/MG_9929.jpg\" alt=\"\" class=\"wp-image-22744\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9929.jpg 680w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9929-300x200.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"680\" height=\"453\" data-id=\"22731\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/MG_9917.jpg\" alt=\"\" class=\"wp-image-22731\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9917.jpg 680w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9917-300x200.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"453\" data-id=\"22750\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/MG_9950.jpg\" alt=\"\" class=\"wp-image-22750\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9950.jpg 680w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9950-300x200.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"453\" data-id=\"22762\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/MG_9954.jpg\" alt=\"\" class=\"wp-image-22762\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9954.jpg 680w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9954-300x200.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"453\" data-id=\"22737\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/MG_9924.jpg\" alt=\"\" class=\"wp-image-22737\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9924.jpg 680w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/MG_9924-300x200.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Calvary City Church Taman Tan Sri Yaacob Jobor Bharu buscando una ampliaci\u00f3n de su actual local de culto, se ha convertido en la primera iglesia de Malasia en instalar el line array K-LA28 de Audiocenter. De ser una peque\u00f1a iglesia basada en una tienda, actualmente se ha expandido a un espacio de culto de 8000&hellip;<\/p>\n","protected":false},"author":1,"featured_media":22761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[357,445],"tags":[],"class_list":["post-29168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-empresa","category-sonido-instalado","category-357","category-445","description-off"],"_links":{"self":[{"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/posts\/29168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/comments?post=29168"}],"version-history":[{"count":3,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/posts\/29168\/revisions"}],"predecessor-version":[{"id":31463,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/posts\/29168\/revisions\/31463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/media\/22761"}],"wp:attachment":[{"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/media?parent=29168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/categories?post=29168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/audiocenter.com\/es\/wp-json\/wp\/v2\/tags?post=29168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}