{"id":29821,"date":"2023-08-11T11:30:23","date_gmt":"2023-08-11T03:30:23","guid":{"rendered":"http:\/\/audiocenter.cc\/product\/k-la28\/"},"modified":"2024-06-27T19:08:59","modified_gmt":"2024-06-27T11:08:59","slug":"k-la28","status":"publish","type":"product","link":"https:\/\/audiocenter.com\/fr\/produit\/k-la28\/","title":{"rendered":"K-LA28"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"29821\" class=\"elementor elementor-29821 elementor-23482\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73b112a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73b112a1\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-797697b7\" data-id=\"797697b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11878a8c split-breadcrumbs-y elementor-widget elementor-widget-the7-breadcrumb\" data-id=\"11878a8c\" data-element_type=\"widget\" data-widget_type=\"the7-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"assistive-text\">Vous \u00eates ici :<\/div><ol class=\"breadcrumbs text-small rcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/audiocenter.com\/fr\/\" title=\"Accueil\"><span itemprop=\"name\">Accueil<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><\/li><li class=\"current\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Product<\/span><meta itemprop=\"position\" content=\"2\" \/><\/li><\/ol>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-70d8d7d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70d8d7d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f090f98\" data-id=\"1f090f98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1d7933a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d7933a8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-18703177\" data-id=\"18703177\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f96a158 lightbox-on-click-y thumbs-col-num-6 elementor-widget__width-initial preserve-gallery-ratio-y show-image-zoom-yes preserve-thumb-ratio-y gallery-nav-display-hover thumbs-nav-display-hover onsale-h-position-left onsale-v-position-top elementor-widget elementor-widget-the7-woocommerce-product-images\" data-id=\"f96a158\" data-element_type=\"widget\" data-widget_type=\"the7-woocommerce-product-images.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"dt-wc-product-gallery the7-elementor-widget the7-woocommerce-product-images-f96a158 thumb-position-bottom\"  data-animation=\"slide\" >        <div class=\"dt-product-gallery\">\n            <div class=\"dt-product-gallery-wrap\">\n\t\t\t\t                <div class=\"flexslider\">\n                    <ul class=\"slides\">\n\t\t\t\t\t\t<li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs.webp\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"k-la28-8pcs\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back.webp\"><img decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"k-la28 retour\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la.webp\"><img decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"k-la\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"k-la28\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li>                    <\/ul>\n\n\t\t\t\t\t        <ul class=\"flex-direction-nav\">\n            <li class=\"flex-nav-prev\"><a href=\"#\" class=\"flex-prev\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i>            <\/a><\/li>\n            <li class=\"flex-nav-next\"><a href=\"#\" class=\"flex-next\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>            <\/a><\/li>\n        <\/ul>\n\t\t                <\/div>\n            <\/div>\n        <\/div>\n\t\t            <div class=\"dt-product-thumbs  \"  data-scroll-mode=\"horizontal\">\n                <div class=\"flexslider\">\n                    <ul class=\"slides\">\n\t\t\t\t\t\t<li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"k-la28-8pcs\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-8pcs.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"k-la28 retour\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-back.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"k-la\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"k-la28\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28.webp\"\/><\/div><\/li>                    <\/ul>\n\t\t\t\t\t        <ul class=\"flex-direction-nav\">\n            <li class=\"flex-nav-prev\"><a href=\"#\" class=\"flex-prev\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i>            <\/a><\/li>\n            <li class=\"flex-nav-next\"><a href=\"#\" class=\"flex-next\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>            <\/a><\/li>\n        <\/ul>\n\t\t                <\/div>\n            <\/div>\n\t\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dfa813a elementor-widget elementor-widget-menu-anchor\" data-id=\"5dfa813a\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"vuedensemble\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14a96dc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14a96dc8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7a9f4f6c\" data-id=\"7a9f4f6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a1e1142 elementor-widget elementor-widget-heading\" data-id=\"2a1e1142\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Vue d'ensemble<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33ccc3c2 elementor-widget elementor-widget-spacer\" data-id=\"33ccc3c2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2330f9 elementor-widget elementor-widget-text-editor\" data-id=\"4b2330f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le K-LA28 est un haut-parleur line array \u00e0 crossover passif, con\u00e7u pour r\u00e9pondre aux exigences \u00e9lev\u00e9es des tourn\u00e9es, des locations et des installations fixes.<\/p>\n<p>Le haut-parleur HF du K-LA28 est un haut-parleur personnalis\u00e9 avec membrane composite (bobine mobile de 1,75&#8243;), et le haut-parleur MF\/LF est un haut-parleur personnalis\u00e9 de 8&#8243; (bobine mobile de 2&#8243;).<\/p>\n<p>Le syst\u00e8me K-LA28 peut \u00eatre utilis\u00e9 comme sonorisation principale pour la sc\u00e8ne avec 3 caissons au minimum ou 16 caissons au maximum par array.<br \/>\nPour l&#8217;application du syst\u00e8me, nous sugg\u00e9rons un ampli pour alimenter deux enceintes (l&#8217;ampli fonctionne avec une imp\u00e9dance de 2 ohms).<br \/>\nAvec l&#8217;Audiocenter CA450, un syst\u00e8me &#8220;plug&amp;play&#8221; peut \u00eatre construit facilement pour r\u00e9pondre aux exigences d&#8217;une petite ou d&#8217;une grande sonorisation.  <\/p>\n<p>K-LA28 peut \u00eatre install\u00e9 verticalement.<br \/>\nLes accessoires de suspension sont int\u00e9gr\u00e9s dans l&#8217;armoire.<br \/>\nLes broches ont un diam\u00e8tre de 8,5 mm et sont tr\u00e8s r\u00e9sistantes.<br \/>\nLe syst\u00e8me peut \u00eatre configur\u00e9 de mani\u00e8re modulaire en fonction des lieux.<br \/>\nLe m\u00eame cadre peut \u00eatre utilis\u00e9 pour faire voler les tableaux ou pour les empiler (nous sugg\u00e9rons un maximum de 4 pi\u00e8ces pour l&#8217;empilage).<br \/>\nPour faciliter l&#8217;utilisation, 3 K-LA28 peuvent \u00eatre empil\u00e9s avec le support horizontal personnalis\u00e9 \u00e0 trois bo\u00eetes.     <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f36e91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f36e91\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a81f2e\" data-id=\"4a81f2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c89175 elementor-widget elementor-widget-menu-anchor\" data-id=\"0c89175\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"cl\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c52f598 elementor-widget elementor-widget-heading\" data-id=\"c52f598\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Caract\u00e9ristiques principales<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d6c612 elementor-widget elementor-widget-spacer\" data-id=\"1d6c612\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a38352 elementor-widget elementor-widget-text-editor\" data-id=\"4a38352\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul>\n<li>Conducteurs sur mesure<\/li>\n<li>La conception du pavillon HF PTV assure une couverture uniforme et une directivit\u00e9 tr\u00e8s pr\u00e9cise.<\/li>\n<li>Condensateur audio am\u00e9ricain Benelec XPP de qualit\u00e9 stable et aux performances fiables<\/li>\n<li>Panneau de fibres soud\u00e9 manuellement pour garantir une consommation nulle, m\u00eame en cas de dynamique tr\u00e8s \u00e9lev\u00e9e.<\/li>\n<li>Circuit unique de protection du conducteur et syst\u00e8me de refroidissement tr\u00e8s efficace du conducteur<\/li>\n<li>Conception optimis\u00e9e et compacte de l&#8217;armoire l\u00e9g\u00e8re<\/li>\n<li>Armoire en contreplaqu\u00e9 de bouleau sans humidit\u00e9, solide comme le roc, fabriqu\u00e9e par CNC<\/li>\n<li>Nombreux accessoires adapt\u00e9s \u00e0 diff\u00e9rentes applications<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa255f elementor-align-center elementor-widget elementor-widget-global elementor-global-37210 elementor-global-36241 elementor-widget-the7_button_widget\" data-id=\"0aa255f\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-lg\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66fea679 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66fea679\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f7c041a\" data-id=\"f7c041a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aa228e7 elementor-widget elementor-widget-menu-anchor\" data-id=\"5aa228e7\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"spcifications\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-313a0ab7 elementor-widget elementor-widget-heading\" data-id=\"313a0ab7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sp\u00e9cifications<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60709ba1 elementor-widget elementor-widget-spacer\" data-id=\"60709ba1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7396448d elementor-widget elementor-widget-text-editor\" data-id=\"7396448d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<table width=\"975\">\n<tbody>\n<tr>\n<td width=\"435\">\n<p>Type  <\/p>\n<\/td>\n<td width=\"531\">\n<p>Haut-parleur line array \u00e0 crossover passif<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Puissance nominale (norme AES)<\/p>\n<\/td>\n<td width=\"531\">\n<p>400W <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>R\u00e9ponse en fr\u00e9quence (-10dB)<\/p>\n<\/td>\n<td width=\"531\">\n<p>60Hz-20kHz<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Couverture horizontale<\/p>\n<\/td>\n<td width=\"531\">\n<p>100\u00b0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Couverture verticale<\/p>\n<\/td>\n<td width=\"531\">\n<p>D\u00e9pend de l&#8217;angle d&#8217;\u00e9jection<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>SPL maximum calcul\u00e9\/1M (continu\/cr\u00eate)<\/p>\n<\/td>\n<td width=\"531\">\n<p>122dB\/128dB<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Conducteur HF<\/p>\n<\/td>\n<td width=\"531\">\n<p>Haut-parleur personnalis\u00e9, bobine vocale de 1,75&#8243; et sortie de 1,0&#8243;.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Conducteur LF<\/p>\n<\/td>\n<td width=\"531\">\n<p>Haut-parleur 2&#215;8&#8243; personnalis\u00e9, bobine vocale de 2,0 pouces<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Imp\u00e9dance nominale<\/p>\n<\/td>\n<td width=\"531\">\n<p>4\u03a9<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Mode crois\u00e9<\/p>\n<\/td>\n<td width=\"531\">\n<p>Passif<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Points de croisement<\/p>\n<\/td>\n<td width=\"531\">\n<p>450Hz &amp; 2,2kHz<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Connecteurs  <\/p>\n<\/td>\n<td width=\"531\">\n<p>Speakon 4Pin<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" width=\"969\">\n<p>Cabinet<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Mat\u00e9riau de l&#8217;armoire<\/p>\n<\/td>\n<td width=\"531\">\n<p>Contreplaqu\u00e9 de bouleau baltique multicouche fabriqu\u00e9 par CNC<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>R\u00e9glage de l&#8217;angle<\/p>\n<\/td>\n<td width=\"531\">\n<p>0\u00b0, 2\u00b0, 4\u00b0, 6\u00b0, 8\u00b0, 10\u00b0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Couleur de l&#8217;armoire<\/p>\n<\/td>\n<td width=\"531\">\n<p>Le noir est la couleur par d\u00e9faut. Contactez Audiocenter pour une personnalisation<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Grille<\/p>\n<\/td>\n<td width=\"531\">\n<p>Maille de fer<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Poign\u00e9es<\/p>\n<\/td>\n<td width=\"531\">\n<p>2 c\u00f4t\u00e9s<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Montage sur poteau<\/p>\n<\/td>\n<td width=\"531\">\n<p>\/<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Accessoires en option<\/p>\n<\/td>\n<td width=\"531\">\n<p>Flightcase avec roues de 100 mm \/ Sac de pluie durable \/ Cadre de vol<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Dimensions de l&#8217;enceinte (L\u00d7H\u00d7P)<\/p>\n<\/td>\n<td width=\"531\">\n<p>590\u00d7236\u00d7436mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Dimensions du carton (L\u00d7H\u00d7P)<\/p>\n<\/td>\n<td width=\"531\">\n<p>325\u00d7690\u00d7534mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Poids net<\/p>\n<\/td>\n<td width=\"531\">\n<p>19,0 kg<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"435\">\n<p>Poids d&#8217;exp\u00e9dition<\/p>\n<\/td>\n<td width=\"531\">\n<p>22,0 kg<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a194c9a elementor-align-center elementor-widget elementor-widget-global elementor-global-37210 elementor-global-36241 elementor-widget-the7_button_widget\" data-id=\"a194c9a\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-lg\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b8862e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b8862e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-23845f24\" data-id=\"23845f24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21abedce elementor-widget elementor-widget-menu-anchor\" data-id=\"21abedce\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Accessoires\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-460514ab elementor-widget elementor-widget-heading\" data-id=\"460514ab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dessin<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4909ea6d elementor-widget elementor-widget-spacer\" data-id=\"4909ea6d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da3a8fd elementor-widget elementor-widget-image\" data-id=\"da3a8fd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"336\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-dim.webp\" class=\"attachment-large size-large wp-image-23344\" alt=\"\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-dim.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-dim-1000x328.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-dim-300x98.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-dim-768x252.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d58dd62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d58dd62\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-72d036a\" data-id=\"72d036a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29f3cf1 elementor-widget elementor-widget-menu-anchor\" data-id=\"29f3cf1\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Graphiques\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bca722 elementor-widget elementor-widget-heading\" data-id=\"4bca722\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Accessoires<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ccfd4f elementor-widget elementor-widget-spacer\" data-id=\"1ccfd4f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e851df7 elementor-widget elementor-widget-image\" data-id=\"e851df7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"460\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-acc.webp\" class=\"attachment-large size-large wp-image-23338\" alt=\"\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-acc.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-acc-1000x449.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-acc-300x135.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/k-la28-acc-768x345.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e9ab7cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9ab7cc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-750a399\" data-id=\"750a399\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39926b4 elementor-widget elementor-widget-menu-anchor\" data-id=\"39926b4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Installations\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8473e99 elementor-widget elementor-widget-heading\" data-id=\"8473e99\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Installations<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c426def elementor-widget elementor-widget-spacer\" data-id=\"c426def\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0fa4d2 elementor-widget elementor-widget-image\" data-id=\"d0fa4d2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2023\/08\/k-la28-install.webp\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a943ca3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a943ca3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6791e9b1\" data-id=\"6791e9b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f8bb0ca elementor-widget elementor-widget-menu-anchor\" data-id=\"3f8bb0ca\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"tlchargements\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fea8c4 elementor-widget elementor-widget-heading\" data-id=\"7fea8c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9chargements<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-216b78b elementor-widget elementor-widget-spacer\" data-id=\"216b78b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32a6ee82 elementor-widget elementor-widget-text-editor\" data-id=\"32a6ee82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2024\/06\/K-LA28.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000; text-decoration: underline;\">K-LA28 Catalogue des produits<\/span><\/a><\/span><\/p>\n<p><span style=\"text-decoration: underline;\"><a href=\"https:\/\/audiocenter.net\/wp-content\/uploads\/2024\/06\/K-LA.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000; text-decoration: underline;\">S\u00e9rie K-LA Catalogue des produits<\/span><\/a><\/span><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f698c68 elementor-align-center elementor-widget elementor-widget-global elementor-global-37210 elementor-global-36241 elementor-widget-the7_button_widget\" data-id=\"f698c68\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-lg\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d6a39c elementor-widget elementor-widget-spacer\" data-id=\"12d6a39c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cca659f\" data-id=\"1cca659f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cfff840 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfff840\" data-element_type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky_offset&quot;:&quot;150&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7e57bedf\" data-id=\"7e57bedf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56ef280 elementor-widget elementor-widget-heading\" data-id=\"56ef280\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">K-LA28<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38ddda9e elementor-widget elementor-widget-heading\" data-id=\"38ddda9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Haut-parleur line array double 8\" \u00e0 crossover passif<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d0cba8a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5d0cba8a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4838605f elementor-widget elementor-widget-text-editor\" data-id=\"4838605f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le K-LA28 est un haut-parleur line array \u00e0 crossover passif, con\u00e7u pour r\u00e9pondre aux exigences \u00e9lev\u00e9es des tourn\u00e9es, des locations et des installations fixes.<\/p>\n<ul>\n<li><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"#overview\">Vue d&#8217;ensemble<\/a><\/span><\/li>\n<li><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"#key\">Caract\u00e9ristiques principales<\/a><\/span><\/li>\n<li><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"#specifications\">Sp\u00e9cifications<\/a><\/span><\/li>\n<li><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"#drawing\">Dessin<\/a><\/span><\/li>\n<li><a href=\"#Accessories\"><span style=\"text-decoration: underline\"><span style=\"color: #ffffff;text-decoration: underline\">Accessoires<\/span><\/span><\/a><\/li>\n<li><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"#Installations\">Installations<\/a><\/span><\/li>\n<li><span style=\"color: #ffffff\"><a style=\"color: #ffffff\" href=\"#downloads\">T\u00e9l\u00e9chargements<\/a><\/span><\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c21462b elementor-align-center elementor-widget elementor-widget-global elementor-global-37200 elementor-global-36244 elementor-widget-the7_button_widget\" data-id=\"c21462b\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-md\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d316e86 elementor-widget elementor-widget-spacer\" data-id=\"5d316e86\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cc5099 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cc5099\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-115fb03a\" data-id=\"115fb03a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a1f4008 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a1f4008\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-448d6c1b\" data-id=\"448d6c1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6326c0 elementor-widget elementor-widget-heading\" data-id=\"7c6326c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Affaires connexes<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5bd975 elementor-widget elementor-widget-spacer\" data-id=\"2f5bd975\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6929fc48 preserve-img-ratio-cover elementor-widget elementor-widget-the7_elements\" data-id=\"6929fc48\" data-element_type=\"widget\" data-widget_type=\"the7_elements.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"portfolio-shortcode the7-elementor-widget the7_elements-6929fc48 mode-masonry classic-layout-list description-under-image quick-scale-img meta-info-off content-bg-on resize-by-browser-width loading-effect-none jquery-filter\" data-padding=\"15px\" data-mobile-columns-num=\"1\" data-tablet-columns-num=\"2\" data-desktop-columns-num=\"3\" data-wide-desktop-columns-num=\"3\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-scroll-offset=\"\"><div class=\"iso-container dt-isotope custom-iso-columns\"><div class=\"visible wf-cell iso-item\" data-post-id=\"49166\" data-date=\"2026-04-01T17:12:18+08:00\" data-name=\"Succ\u00e8s de la d\u00e9monstration de la s\u00e9rie Avanda au P\u00e9rou\"><article class=\"post visible no-img post-49166 type-post status-publish format-standard hentry category-non-classifiee category-241 description-off\" data-name=\"Succ\u00e8s de la d\u00e9monstration de la s\u00e9rie Avanda au P\u00e9rou\" data-date=\"2026-04-01T17:12:18+08:00\">\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"ele-entry-title\"><a href=\"https:\/\/audiocenter.com\/fr\/succes-de-la-demonstration-de-la-serie-avanda-au-perou\/\" rel=\"bookmark\" title=\"Succ\u00e8s de la d\u00e9monstration de la s\u00e9rie Avanda au P\u00e9rou\">Succ\u00e8s de la d\u00e9monstration de la s\u00e9rie Avanda au P\u00e9rou<\/a><\/h3>\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"49180\" data-date=\"2026-03-23T17:15:29+08:00\" data-name=\"\u00a1Pr\u00e9sentation de la derni\u00e8re exp\u00e9rience Audiocenter \u00e0 Quito, \u00c9quateur !\"><article class=\"post visible no-img post-49180 type-post status-publish format-standard hentry category-non-classifiee category-241 description-off\" data-name=\"\u00a1Pr\u00e9sentation de la derni\u00e8re exp\u00e9rience Audiocenter \u00e0 Quito, \u00c9quateur !\" data-date=\"2026-03-23T17:15:29+08:00\">\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"ele-entry-title\"><a href=\"https:\/\/audiocenter.com\/fr\/presentation-de-la-derniere-experience-audiocenter-a-quito-equateur\/\" rel=\"bookmark\" title=\"\u00a1Pr\u00e9sentation de la derni\u00e8re exp\u00e9rience Audiocenter \u00e0 Quito, \u00c9quateur !\">\u00a1Pr\u00e9sentation de la derni\u00e8re exp\u00e9rience Audiocenter \u00e0 Quito, \u00c9quateur !<\/a><\/h3>\n<\/div><\/article><\/div><div class=\"visible wf-cell iso-item\" data-post-id=\"48745\" data-date=\"2026-03-04T09:07:05+08:00\" data-name=\"Int\u00e9gration technique de l&#039;AVANDA 210A d&#039;Audiocenter au stade Pr\u00edncipe Felipe en Espagne\"><article class=\"post visible post-48745 type-post status-publish format-standard has-post-thumbnail hentry category-non-classifiee category-241 description-off\" data-name=\"Int\u00e9gration technique de l&#8217;AVANDA 210A d&#8217;Audiocenter au stade Pr\u00edncipe Felipe en Espagne\" data-date=\"2026-03-04T09:07:05+08:00\">\n\n\t<div class=\"post-thumbnail-wrap\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Image article\" href=\"https:\/\/audiocenter.com\/fr\/integration-technique-de-lavanda-210a-daudiocenter-au-stade-principe-felipe-en-espagne\/\"><img decoding=\"async\" width=\"1740\" height=\"1160\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201740%201160&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1740px) 100vw, 1740px\" style=\"--ratio: 1740 \/ 1160;\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151.jpg\" loading=\"eager\" data-srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151.jpg 1740w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151-300x200.jpg 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151-1024x683.jpg 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151-768x512.jpg 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151-1536x1024.jpg 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/03\/\u5fae\u4fe1\u56fe\u7247_20260228003200_1334_151-1000x667.jpg 1000w\" \/><\/a>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"ele-entry-title\"><a href=\"https:\/\/audiocenter.com\/fr\/integration-technique-de-lavanda-210a-daudiocenter-au-stade-principe-felipe-en-espagne\/\" rel=\"bookmark\" title=\"Int\u00e9gration technique de l&#8217;AVANDA 210A d&#8217;Audiocenter au stade Pr\u00edncipe Felipe en Espagne\">Int\u00e9gration technique de l&#8217;AVANDA 210A d&#8217;Audiocenter au stade Pr\u00edncipe Felipe en Espagne<\/a><\/h3>\n<\/div><\/article><\/div><\/div><!-- iso-container|iso-grid --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p class=\"sub-title\">  Haut-parleur passif Line Array, 400W<\/p>\n<div class=\"short-description-text\">\n<p><strong>Niveau de pression acoustique maximal : <\/strong> 128 dB<\/p>\n<p><strong>Dimension(WxHxD) : <\/strong> 590\u00d7236\u00d7436mm<\/p>\n<\/div>\n","protected":false},"featured_media":23286,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":[],"product_cat":[598,472],"product_tag":[],"class_list":{"0":"post-29821","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-k-la28-fr","7":"product_cat-serie-k-la","8":"category-241","9":"description-off","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product\/29821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/comments?post=29821"}],"version-history":[{"count":6,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product\/29821\/revisions"}],"predecessor-version":[{"id":40861,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product\/29821\/revisions\/40861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/media\/23286"}],"wp:attachment":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/media?parent=29821"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product_cat?post=29821"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product_tag?post=29821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}