{"id":49941,"date":"2026-07-15T11:40:22","date_gmt":"2026-07-15T03:40:22","guid":{"rendered":"https:\/\/audiocenter.com\/?post_type=product&#038;p=49941"},"modified":"2026-07-15T17:27:15","modified_gmt":"2026-07-15T09:27:15","slug":"avanda-712a","status":"publish","type":"product","link":"https:\/\/audiocenter.com\/fr\/product\/avanda-712a\/","title":{"rendered":"AVANDA 712A"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"49941\" class=\"elementor elementor-49941\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-471fd70d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"471fd70d\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87aa15e\" data-id=\"87aa15e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d73ddc split-breadcrumbs-y elementor-widget elementor-widget-the7-breadcrumb\" data-id=\"2d73ddc\" data-element_type=\"widget\" data-widget_type=\"the7-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"assistive-text\">Vous \u00eates ici :<\/div><ol class=\"breadcrumbs text-small rcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/audiocenter.com\/fr\/\" title=\"Accueil\"><span itemprop=\"name\">Accueil<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><\/li><li class=\"current\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\">Product<\/span><meta itemprop=\"position\" content=\"2\" \/><\/li><\/ol>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1529a7c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1529a7c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3342abe5\" data-id=\"3342abe5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-25d19d8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25d19d8e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6f43585a\" data-id=\"6f43585a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35d540c lightbox-on-click-y thumbs-col-num-6 elementor-widget__width-initial preserve-gallery-ratio-y show-image-zoom-yes preserve-thumb-ratio-y gallery-nav-display-hover thumbs-nav-display-hover onsale-h-position-left onsale-v-position-top elementor-widget elementor-widget-the7-woocommerce-product-images\" data-id=\"35d540c\" data-element_type=\"widget\" data-widget_type=\"the7-woocommerce-product-images.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"dt-wc-product-gallery the7-elementor-widget the7-woocommerce-product-images-35d540c thumb-position-bottom\"  data-animation=\"slide\" >        <div class=\"dt-product-gallery\">\n            <div class=\"dt-product-gallery-wrap\">\n\t\t\t\t                <div class=\"flexslider\">\n                    <ul class=\"slides\">\n\t\t\t\t\t\t<li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A.webp\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"AVANDA 712A\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back.webp\"><img decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"AVANDA 712A back\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front.webp\"><img decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"AVANDA 712A Front\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"AVANDA 712A Side\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li><li class=\"woocommerce-product-gallery__image\"><a href=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"619\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-1000x619.webp\" class=\"wp-post-image\" alt=\"\" title=\"AVANDA -11\" data-caption=\"\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11.webp\" data-large_image=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11.webp\" data-large_image_width=\"2480\" data-large_image_height=\"1535\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-1000x619.webp 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-300x186.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-1024x634.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-768x475.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-1536x951.webp 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-2048x1268.webp 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/li>                    <\/ul>\n\n\t\t\t\t\t        <ul class=\"flex-direction-nav\">\n            <li class=\"flex-nav-prev\"><a href=\"#\" class=\"flex-prev\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i>            <\/a><\/li>\n            <li class=\"flex-nav-next\"><a href=\"#\" class=\"flex-next\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>            <\/a><\/li>\n        <\/ul>\n\t\t                <\/div>\n            <\/div>\n        <\/div>\n\t\t            <div class=\"dt-product-thumbs  \"  data-scroll-mode=\"horizontal\">\n                <div class=\"flexslider\">\n                    <ul class=\"slides\">\n\t\t\t\t\t\t<li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"AVANDA 712A\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"AVANDA 712A back\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-back.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"AVANDA 712A Front\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Front.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"AVANDA 712A Side\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-712A-Side.webp\"\/><\/div><\/li><li title=\"\"><div class=\"slide-wrapper\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me aspect\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-500x309.webp\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-500x309.webp 500w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11-1000x618.webp 1000w\" style=\"--ratio: 500 \/ 309\" sizes=\"(max-width: 500px) 100vw, 500px\" alt=\"\" title=\"AVANDA -11\" width=\"500\" height=\"309\"  data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/AVANDA-11.webp\"\/><\/div><\/li>                    <\/ul>\n\t\t\t\t\t        <ul class=\"flex-direction-nav\">\n            <li class=\"flex-nav-prev\"><a href=\"#\" class=\"flex-prev\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i>            <\/a><\/li>\n            <li class=\"flex-nav-next\"><a href=\"#\" class=\"flex-next\" aria-hidden =\"true\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>            <\/a><\/li>\n        <\/ul>\n\t\t                <\/div>\n            <\/div>\n\t\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aafa001 elementor-widget elementor-widget-menu-anchor\" data-id=\"5aafa001\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"overview\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19b7ceb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19b7ceb4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-634afbf2\" data-id=\"634afbf2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15962723 elementor-widget elementor-widget-heading\" data-id=\"15962723\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Overview<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3156eee1 elementor-widget elementor-widget-spacer\" data-id=\"3156eee1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f067ee5 elementor-widget elementor-widget-text-editor\" data-id=\"f067ee5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The AVANDA 712A is a professional 12-inch two-way active point-source loudspeaker with excellent sound quality and reliable performance, perfectly suited for high-quality live sound reinforcement scenarios.<\/p><p>It is equipped with a 3.0-inch voice coil, 1.4-inch exit neodymium driver and 12-inch neodymium woofer , paired with a dual-channel 3000W power amplifier. The horn provides uniform sound coverage of 100 x 60\u00b0, achieving a maximum sound pressure level of 132dB for premium and pristine audio output.<\/p><p>Built around precision-tuned FIR DSP, AVANDA 712A achieves optimized transient response, explosive dynamics and crystalline detail &#8211; all anchored by deep, tightly controlled bass that honors the integrity of the original signal.<\/p><p>The enclosure is constructed from premium-grade plywood, precision-machined via CNC and finished with a polyurea coating for waterproofing, abrasion resistance, and high-temperature durability. Its compact, symmetrical design ensures structural stability and practical deployment, while the base supports 0 \u00b0 \/10\u00b0 mounting angles to accommodate a wide range of sound reinforcement applications.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c597068 elementor-align-center elementor-widget elementor-widget-global elementor-global-37210 elementor-global-36241 elementor-widget-the7_button_widget\" data-id=\"c597068\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-lg\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cde2b69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cde2b69\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3f743910\" data-id=\"3f743910\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7c69e4 elementor-widget elementor-widget-menu-anchor\" data-id=\"d7c69e4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"specifications\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd57350 elementor-widget elementor-widget-heading\" data-id=\"1fd57350\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Specifications<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ee3f3ad elementor-widget elementor-widget-spacer\" data-id=\"3ee3f3ad\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6656807b elementor-widget elementor-widget-text-editor\" data-id=\"6656807b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<table width=\"975\"><tbody><tr><td width=\"435\"><p>Type\u00a0\u00a0<\/p><\/td><td width=\"531\"><p>Active DSP-controlled full range loudspeaker<\/p><\/td><\/tr><tr><td width=\"435\"><p>Frequency Response(-10dB)<\/p><\/td><td width=\"531\"><p>42Hz-20kHz<\/p><\/td><\/tr><tr><td width=\"435\"><p>Horizontal Coverage<\/p><\/td><td width=\"531\"><p>100\u00b0<\/p><\/td><\/tr><tr><td width=\"435\"><p>Vertical Coverage<\/p><\/td><td width=\"531\"><p>60\u00b0<\/p><\/td><\/tr><tr><td width=\"435\"><p>Maximum Calculated SPL\/1M\u00a0(Continuous\/Peak)<\/p><\/td><td width=\"531\"><p>126dB\/132dB<\/p><\/td><\/tr><tr><td width=\"435\"><p>HF Driver<\/p><\/td><td width=\"531\"><p>Customized Neodymium driver, 3.0\u201d voice coil, 1.4\u201d exit<\/p><\/td><\/tr><tr><td width=\"435\"><p>LF Driver<\/p><\/td><td width=\"531\"><p>Customized 12\u201d Neodymium driver, 3.0\u201d voice coil<\/p><\/td><\/tr><tr><td colspan=\"2\" width=\"969\"><p>DSP<\/p><\/td><\/tr><tr><td width=\"435\"><p>Processor<\/p><\/td><td width=\"531\"><p>96kHz signal sampling frequency, FIR filtering<\/p><\/td><\/tr><tr><td width=\"435\"><p>Presets<\/p><\/td><td width=\"531\"><p>MAIN,LF BOOST,W\/SUB<\/p><\/td><\/tr><tr><td colspan=\"2\" width=\"969\"><p>AMPLIFIER<\/p><\/td><\/tr><tr><td width=\"435\"><p>Amplifier Circuitry<\/p><\/td><td width=\"531\"><p>Class D<\/p><\/td><\/tr><tr><td width=\"435\"><p>Power (RMS standards)<\/p><\/td><td width=\"531\"><p>1500W<\/p><\/td><\/tr><tr><td width=\"435\"><p>Peak Power<\/p><\/td><td width=\"531\"><p>3000W<\/p><\/td><\/tr><tr><td width=\"435\"><p>Frequency Response(1W 8\u03a9 2ch)<\/p><\/td><td width=\"531\"><p>20Hz-20kHz(\u00b10.5dB)<\/p><\/td><\/tr><tr><td width=\"435\"><p>Intermodulation Distortion<\/p><\/td><td width=\"531\"><p>\uff1c0.05%<\/p><\/td><\/tr><tr><td width=\"435\"><p>Total Harmonic Distortion<\/p><\/td><td width=\"531\"><p>\uff1c0.05%<\/p><\/td><\/tr><tr><td width=\"435\"><p>Cooling System<\/p><\/td><td width=\"531\"><p>Cooling with fans, air convection<\/p><\/td><\/tr><tr><td width=\"435\"><p>Protection<\/p><\/td><td width=\"531\"><p>DC protection, short circuit protection, overheat protection, input overload protection, output overload protection, soft startup protection, overvoltage protection, undervoltage protection<\/p><\/td><\/tr><tr><td width=\"435\"><p>Signal Input<\/p><\/td><td width=\"531\"><p>Female XLR(Mono jack 6.35)<\/p><\/td><\/tr><tr><td width=\"435\"><p>Signal Output\u00a0<\/p><\/td><td width=\"531\"><p>Male XLR<\/p><\/td><\/tr><tr><td width=\"435\"><p>Power Input<\/p><\/td><td width=\"531\"><p>Power connector<\/p><\/td><\/tr><tr><td width=\"435\"><p>Power Output<\/p><\/td><td width=\"531\"><p>Power connector<\/p><\/td><\/tr><tr><td width=\"435\"><p>Working Voltage<\/p><\/td><td width=\"531\"><p>100&#8211;240V~ (\u00b110%,50\/60Hz\uff09<\/p><\/td><\/tr><tr><td width=\"435\"><p>Power consumption (1\/8 output power)<\/p><\/td><td width=\"531\"><p>149W<\/p><\/td><\/tr><tr><td width=\"435\"><p>CABINET<\/p><\/td><td width=\"531\"><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"435\"><p>Cabinet Material<\/p><\/td><td width=\"531\"><p>CNC machined plywood<\/p><\/td><\/tr><tr><td width=\"435\"><p>Coating<\/p><\/td><td width=\"531\"><p>Durable Polyurea Coating<\/p><\/td><\/tr><tr><td width=\"435\"><p>Cabinet Color<\/p><\/td><td width=\"531\"><p>Black is the default color. Contact Audiocenter for customization<\/p><\/td><\/tr><tr><td width=\"435\"><p>Grille<\/p><\/td><td width=\"531\"><p>Iron mesh<\/p><\/td><\/tr><tr><td width=\"435\"><p>Handles<\/p><\/td><td width=\"531\"><p>2 side<\/p><\/td><\/tr><tr><td width=\"435\"><p>Monitor Angle<\/p><\/td><td width=\"531\"><p>Symmetrical 45\u00b0 monitoring Angle<\/p><\/td><\/tr><tr><td width=\"435\"><p>Hanging Hardwares<\/p><\/td><td width=\"531\"><p>M8 screw<\/p><\/td><\/tr><tr><td width=\"435\"><p>Pole Mount<\/p><\/td><td width=\"531\"><p>Base hole \u03a635mm\uff0c0\u00b0 or 10\u00b0 options<\/p><\/td><\/tr><tr><td width=\"435\"><p>Speaker Dimension (W\u00d7H\u00d7D)<\/p><\/td><td width=\"531\"><p>366x610x385mm<\/p><\/td><\/tr><tr><td width=\"435\"><p>Carton Dimension (W\u00d7H\u00d7D)<\/p><\/td><td width=\"531\"><p>456\u00d7705\u00d7481mm<\/p><\/td><\/tr><tr><td width=\"435\"><p>Net Weight<\/p><\/td><td width=\"531\"><p>20.0kg<\/p><\/td><\/tr><tr><td width=\"435\"><p>Shipping Weight<\/p><\/td><td width=\"531\"><p>23.0kg<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d468811 elementor-align-center elementor-widget elementor-widget-global elementor-global-37210 elementor-global-36241 elementor-widget-the7_button_widget\" data-id=\"d468811\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-lg\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45f99b66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45f99b66\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1f7b3ff1\" data-id=\"1f7b3ff1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bb2655d elementor-widget elementor-widget-menu-anchor\" data-id=\"7bb2655d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"drawing\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2721040 elementor-widget elementor-widget-heading\" data-id=\"2721040\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Drawing<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-436b4232 elementor-widget elementor-widget-spacer\" data-id=\"436b4232\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b96f4a4 elementor-widget elementor-widget-image\" data-id=\"2b96f4a4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"303\" src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/avanda-712a-Dim.webp\" class=\"attachment-large size-large wp-image-49881\" alt=\"\" srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/avanda-712a-Dim.webp 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/avanda-712a-Dim-300x89.webp 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/avanda-712a-Dim-768x227.webp 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2026\/07\/avanda-712a-Dim-1000x296.webp 1000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b987637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b987637\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9fe8430\" data-id=\"9fe8430\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6673d958 elementor-widget elementor-widget-menu-anchor\" data-id=\"6673d958\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"downloads\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-285e8908 elementor-widget elementor-widget-heading\" data-id=\"285e8908\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Downloads<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-790117eb elementor-widget elementor-widget-spacer\" data-id=\"790117eb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea2b938 elementor-widget elementor-widget-text-editor\" data-id=\"6ea2b938\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><span style=\"color: #000000; text-decoration: underline;\">AVANDA 712A Product Datasheet<\/span><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35d319b5 elementor-widget elementor-widget-spacer\" data-id=\"35d319b5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3548278a\" data-id=\"3548278a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c6cf948 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6cf948\" data-element_type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky_offset&quot;:&quot;150&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48068fe5\" data-id=\"48068fe5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f41c042 elementor-widget elementor-widget-heading\" data-id=\"3f41c042\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AVANDA 712A <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77454c6a elementor-widget elementor-widget-heading\" data-id=\"77454c6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Active DSP-controlled full range loudspeaker<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b114290 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7b114290\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3775537f elementor-widget elementor-widget-text-editor\" data-id=\"3775537f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The AVANDA 712A is a professional 12-inch two-way active point-source loudspeaker with excellent sound quality and reliable performance, perfectly suited for high-quality live sound reinforcement scenarios.<\/p><ul><li><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"#overview\">Overview<\/a><\/span><\/li><li><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"#specifications\">Specifications<\/a><\/span><\/li><li><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"#drawing\">Drawing<\/a><\/span><\/li><li><span style=\"text-decoration: underline;\"><a href=\"#Graphs\"><span style=\"color: #ffffff; text-decoration: underline;\">Graphs<\/span><\/a><\/span><\/li><li><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"#downloads\">Downloads<\/a><\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e425f2 elementor-align-center elementor-widget elementor-widget-global elementor-global-37200 elementor-global-36244 elementor-widget-the7_button_widget\" data-id=\"8e425f2\" data-element_type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MTg3IiwidG9nZ2xlIjpmYWxzZX0%3D\" class=\"box-button elementor-button elementor-size-md\">Demande De Devis<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e15ed9 elementor-widget elementor-widget-spacer\" data-id=\"2e15ed9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67bef869 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67bef869\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16985213\" data-id=\"16985213\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3263bcc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3263bcc1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-692f91d3\" data-id=\"692f91d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fa6d06b elementor-widget elementor-widget-heading\" data-id=\"5fa6d06b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Related Cases<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0756d0 elementor-widget elementor-widget-spacer\" data-id=\"1f0756d0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155fed03 preserve-img-ratio-cover elementor-widget elementor-widget-the7_elements\" data-id=\"155fed03\" data-element_type=\"widget\" data-widget_type=\"the7_elements.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"portfolio-shortcode the7-elementor-widget the7_elements-155fed03 mode-masonry classic-layout-list description-under-image quick-scale-img meta-info-off content-bg-on resize-by-browser-width loading-effect-none jquery-filter\" data-padding=\"15px\" data-mobile-columns-num=\"1\" data-tablet-columns-num=\"2\" data-desktop-columns-num=\"3\" data-wide-desktop-columns-num=\"3\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-scroll-offset=\"\"><div class=\"iso-container dt-isotope custom-iso-columns\"><div class=\"visible wf-cell iso-item\" data-post-id=\"31451\" data-date=\"2017-07-16T11:31:00+08:00\" data-name=\"Fou pendant 8 heures ! Audiocenter est toujours \u00e0 vos c\u00f4t\u00e9s !\"><article class=\"post visible post-31451 type-post status-publish format-standard has-post-thumbnail hentry category-etude-de-cas category-son-en-direct tag-k-la-dsp-fr\" data-name=\"Fou pendant 8 heures ! Audiocenter est toujours \u00e0 vos c\u00f4t\u00e9s !\" data-date=\"2017-07-16T11:31:00+08:00\">\n\n\t<div class=\"post-thumbnail-wrap\">\n\t\t<div class=\"post-thumbnail\">\n\n\t\t\t<a class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\" aria-label=\"Image article\" href=\"https:\/\/audiocenter.com\/fr\/fou-pendant-8-heures-audiocenter-est-toujours-a-vos-cotes\/\"><img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%202560%201707&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 2560px) 100vw, 2560px\" style=\"--ratio: 2560 \/ 1707;\" data-src=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-scaled.jpg\" loading=\"eager\" data-srcset=\"https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-scaled.jpg 2560w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-scaled-1000x667.jpg 1000w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-300x200.jpg 300w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-1024x683.jpg 1024w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-768x512.jpg 768w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-1536x1024.jpg 1536w, https:\/\/audiocenter.com\/wp-content\/uploads\/2023\/08\/IMG_5096-2048x1365.jpg 2048w\" \/><\/a>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"post-entry-content\">\n\n\t<h3 class=\"ele-entry-title\"><a href=\"https:\/\/audiocenter.com\/fr\/fou-pendant-8-heures-audiocenter-est-toujours-a-vos-cotes\/\" rel=\"bookmark\" title=\"Fou pendant 8 heures ! Audiocenter est toujours \u00e0 vos c\u00f4t\u00e9s !\">Fou pendant 8 heures ! Audiocenter est toujours \u00e0 vos c\u00f4t\u00e9s !<\/a><\/h3>\n<\/div><\/article><\/div><\/div><!-- iso-container|iso-grid --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p class=\"sub-title\">Active DSP-controlled full range loudspeaker<\/p>\n<div class=\"short-description-text\">\n<p><strong>Peak Power: <\/strong> 3000W<\/p>\n<p><strong>Max SPL: <\/strong> 132dB<\/p>\n<p><strong>Dimension(WxHxD): <\/strong>366\u00d7610\u00d7385mm<\/p>\n<\/div>\n","protected":false},"featured_media":49905,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":[],"product_cat":[156,1221,161],"product_tag":[],"class_list":["post-49941","product","type-product","status-publish","has-post-thumbnail","product_cat-active-point-source","product_cat-avanda-712a","product_cat-avanda-series","first","instock","featured","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product\/49941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/comments?post=49941"}],"version-history":[{"count":12,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product\/49941\/revisions"}],"predecessor-version":[{"id":50014,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product\/49941\/revisions\/50014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/media\/49905"}],"wp:attachment":[{"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/media?parent=49941"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product_cat?post=49941"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/audiocenter.com\/fr\/wp-json\/wp\/v2\/product_tag?post=49941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}